{"id":32535,"date":"2026-05-11T14:05:06","date_gmt":"2026-05-11T14:05:06","guid":{"rendered":"https:\/\/meber2026.graphoservice.it\/product\/art-1362-001-promo\/"},"modified":"2026-05-11T14:05:08","modified_gmt":"2026-05-11T14:05:08","slug":"art-1362-001-promo","status":"publish","type":"product","link":"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/","title":{"rendered":"Art. 1362-001 Promo"},"content":{"rendered":"<p><strong>Sacche quadrate per zaini soccorso USATO\u00a0 buone condizioni<\/strong><\/p>\n<p><strong>Quantit\u00e0<\/strong>:<br \/>\nn. 1 art. 1362-001\/G\u00a0<\/p>\n<p>n. 1 art. 1362-001\/V\u00a0<\/p>\n<p><strong>Prezzo<\/strong>: \u20ac 15,00 cad. (NO VAT)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sacche quadrate per zaini soccorso USATO\u00a0 buone condizioni Quantit\u00e0: n. 1 art. 1362-001\/G\u00a0 n. 1 art. 1362-001\/V\u00a0 Prezzo: \u20ac 15,00 cad. (NO VAT)<\/p>\n","protected":false},"author":1,"featured_media":32688,"parent":0,"menu_order":51,"template":"","meta":{"_acf_changed":false,"footnotes":""},"application-tag":[117],"class_list":["post-32535","product","type-product","status-publish","has-post-thumbnail","hentry","application-tag-promo"],"acf":[],"dsm_author":{"name":"admeb26","avatar_url":"https:\/\/meber2026.graphoservice.it\/wp-content\/plugins\/ultimate-member\/assets\/img\/default_avatar.jpg","archive_link":"https:\/\/meber2026.graphoservice.it\/es\/author\/admeb26\/","biodata":""},"dsm_categories":[],"dsm_attachment_categories":[],"dsm_featured_image":{"thumbnail":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini-150x150.jpg","medium":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini-300x245.jpg","medium_large":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini-768x627.jpg","large":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","1536x1536":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","2048x2048":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","et-pb-post-main-image":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini-400x250.jpg","et-pb-post-main-image-fullwidth":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","et-pb-portfolio-image":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini-400x284.jpg","et-pb-portfolio-module-image":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini-510x382.jpg","et-pb-portfolio-image-single":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","et-pb-gallery-module-image-portrait":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini-400x516.jpg","et-pb-post-main-image-fullwidth-large":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","et-pb-image--responsive--desktop":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","et-pb-image--responsive--tablet":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","et-pb-image--responsive--phone":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini-480x392.jpg","full":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Art. 1362-001 Promo<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Art. 1362-001 Promo\" \/>\n<meta property=\"og:description\" content=\"Sacche quadrate per zaini soccorso USATO\u00a0 buone condizioni Quantit\u00e0: n. 1 art. 1362-001\/G\u00a0 n. 1 art. 1362-001\/V\u00a0 Prezzo: \u20ac 15,00 cad. (NO VAT)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/\" \/>\n<meta property=\"og:site_name\" content=\"Me.Ber.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T14:05:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"637\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/product\\\/art-1362-001-promo\\\/\",\"url\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/product\\\/art-1362-001-promo\\\/\",\"name\":\"Art. 1362-001 Promo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/product\\\/art-1362-001-promo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/product\\\/art-1362-001-promo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Sacche_per_zaini.jpg\",\"datePublished\":\"2026-05-11T14:05:06+00:00\",\"dateModified\":\"2026-05-11T14:05:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/product\\\/art-1362-001-promo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/product\\\/art-1362-001-promo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/product\\\/art-1362-001-promo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Sacche_per_zaini.jpg\",\"contentUrl\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Sacche_per_zaini.jpg\",\"width\":780,\"height\":637},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/product\\\/art-1362-001-promo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art. 1362-001 Promo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/\",\"name\":\"Me.Ber.\",\"description\":\"In Case of Emergerncy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Art. 1362-001 Promo","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Art. 1362-001 Promo","og_description":"Sacche quadrate per zaini soccorso USATO\u00a0 buone condizioni Quantit\u00e0: n. 1 art. 1362-001\/G\u00a0 n. 1 art. 1362-001\/V\u00a0 Prezzo: \u20ac 15,00 cad. (NO VAT)","og_url":"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/","og_site_name":"Me.Ber.","article_modified_time":"2026-05-11T14:05:08+00:00","og_image":[{"width":780,"height":637,"url":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/","url":"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/","name":"Art. 1362-001 Promo","isPartOf":{"@id":"https:\/\/meber2026.graphoservice.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/#primaryimage"},"image":{"@id":"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/#primaryimage"},"thumbnailUrl":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","datePublished":"2026-05-11T14:05:06+00:00","dateModified":"2026-05-11T14:05:08+00:00","breadcrumb":{"@id":"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/#primaryimage","url":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","contentUrl":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/Sacche_per_zaini.jpg","width":780,"height":637},{"@type":"BreadcrumbList","@id":"https:\/\/meber2026.graphoservice.it\/es\/product\/art-1362-001-promo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/meber2026.graphoservice.it\/es\/"},{"@type":"ListItem","position":2,"name":"Art. 1362-001 Promo"}]},{"@type":"WebSite","@id":"https:\/\/meber2026.graphoservice.it\/es\/#website","url":"https:\/\/meber2026.graphoservice.it\/es\/","name":"Me.Ber.","description":"In Case of Emergerncy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meber2026.graphoservice.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/meber2026.graphoservice.it\/es\/wp-json\/wp\/v2\/product\/32535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meber2026.graphoservice.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meber2026.graphoservice.it\/es\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/meber2026.graphoservice.it\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/meber2026.graphoservice.it\/es\/wp-json\/wp\/v2\/product\/32535\/revisions"}],"predecessor-version":[{"id":32959,"href":"https:\/\/meber2026.graphoservice.it\/es\/wp-json\/wp\/v2\/product\/32535\/revisions\/32959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meber2026.graphoservice.it\/es\/wp-json\/wp\/v2\/media\/32688"}],"wp:attachment":[{"href":"https:\/\/meber2026.graphoservice.it\/es\/wp-json\/wp\/v2\/media?parent=32535"}],"wp:term":[{"taxonomy":"application-tag","embeddable":true,"href":"https:\/\/meber2026.graphoservice.it\/es\/wp-json\/wp\/v2\/application-tag?post=32535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}