{"id":32483,"date":"2026-05-11T14:04:52","date_gmt":"2026-05-11T14:04:52","guid":{"rendered":"https:\/\/meber2026.graphoservice.it\/product\/art-19140\/"},"modified":"2026-05-11T14:04:52","modified_gmt":"2026-05-11T14:04:52","slug":"art-19140","status":"publish","type":"product","link":"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/","title":{"rendered":"Art. 19140"},"content":{"rendered":"<p><strong>Art. 19140\u00a0Double space stretcher support with 350 mm ramp USED<\/p>\n<p>Quantity<\/strong>: 1<\/p>\n<p><strong>Price<\/strong>: 480,00 \u20ac (NO VAT)<\/p>\n<p>LOT 001; 2008-05<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art. 19140\u00a0Double space stretcher support with 350 mm ramp USED Quantity: 1 Price: 480,00 \u20ac (NO VAT) LOT 001; 2008-05<\/p>\n","protected":false},"author":1,"featured_media":32707,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"application-tag":[115],"class_list":["post-32483","product","type-product","status-publish","has-post-thumbnail","hentry","application-tag-promo"],"acf":[],"dsm_author":{"name":"admeb26","avatar_url":"https:\/\/meber2026.graphoservice.it\/wp-content\/plugins\/ultimate-member\/assets\/img\/default_avatar.jpg","archive_link":"https:\/\/meber2026.graphoservice.it\/en\/author\/admeb26\/","biodata":""},"dsm_categories":[],"dsm_attachment_categories":[],"dsm_featured_image":{"thumbnail":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO-150x150.jpg","medium":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO-300x169.jpg","medium_large":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","large":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","1536x1536":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","2048x2048":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","et-pb-post-main-image":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO-400x250.jpg","et-pb-post-main-image-fullwidth":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","et-pb-portfolio-image":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO-400x284.jpg","et-pb-portfolio-module-image":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO-510x382.jpg","et-pb-portfolio-image-single":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","et-pb-gallery-module-image-portrait":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO-400x422.jpg","et-pb-post-main-image-fullwidth-large":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","et-pb-image--responsive--desktop":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","et-pb-image--responsive--tablet":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","et-pb-image--responsive--phone":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO-480x270.jpg","full":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Art. 19140<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Art. 19140\" \/>\n<meta property=\"og:description\" content=\"Art. 19140\u00a0Double space stretcher support with 350 mm ramp USED Quantity: 1 Price: 480,00 \u20ac (NO VAT) LOT 001; 2008-05\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/\" \/>\n<meta property=\"og:site_name\" content=\"Me.Ber.\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/product\\\/art-19140\\\/\",\"url\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/product\\\/art-19140\\\/\",\"name\":\"Art. 19140\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/product\\\/art-19140\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/product\\\/art-19140\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/MTX2_PROMO.jpg\",\"datePublished\":\"2026-05-11T14:04:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/product\\\/art-19140\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/product\\\/art-19140\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/product\\\/art-19140\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/MTX2_PROMO.jpg\",\"contentUrl\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/MTX2_PROMO.jpg\",\"width\":750,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/product\\\/art-19140\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art. 19140\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/\",\"name\":\"Me.Ber.\",\"description\":\"In Case of Emergerncy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meber2026.graphoservice.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Art. 19140","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Art. 19140","og_description":"Art. 19140\u00a0Double space stretcher support with 350 mm ramp USED Quantity: 1 Price: 480,00 \u20ac (NO VAT) LOT 001; 2008-05","og_url":"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/","og_site_name":"Me.Ber.","og_image":[{"width":750,"height":422,"url":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/","url":"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/","name":"Art. 19140","isPartOf":{"@id":"https:\/\/meber2026.graphoservice.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/#primaryimage"},"image":{"@id":"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/#primaryimage"},"thumbnailUrl":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","datePublished":"2026-05-11T14:04:52+00:00","breadcrumb":{"@id":"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/#primaryimage","url":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","contentUrl":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/05\/MTX2_PROMO.jpg","width":750,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/meber2026.graphoservice.it\/en\/product\/art-19140\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/meber2026.graphoservice.it\/en\/"},{"@type":"ListItem","position":2,"name":"Art. 19140"}]},{"@type":"WebSite","@id":"https:\/\/meber2026.graphoservice.it\/en\/#website","url":"https:\/\/meber2026.graphoservice.it\/en\/","name":"Me.Ber.","description":"In Case of Emergerncy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meber2026.graphoservice.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/meber2026.graphoservice.it\/en\/wp-json\/wp\/v2\/product\/32483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meber2026.graphoservice.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meber2026.graphoservice.it\/en\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/meber2026.graphoservice.it\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/meber2026.graphoservice.it\/en\/wp-json\/wp\/v2\/product\/32483\/revisions"}],"predecessor-version":[{"id":32914,"href":"https:\/\/meber2026.graphoservice.it\/en\/wp-json\/wp\/v2\/product\/32483\/revisions\/32914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meber2026.graphoservice.it\/en\/wp-json\/wp\/v2\/media\/32707"}],"wp:attachment":[{"href":"https:\/\/meber2026.graphoservice.it\/en\/wp-json\/wp\/v2\/media?parent=32483"}],"wp:term":[{"taxonomy":"application-tag","embeddable":true,"href":"https:\/\/meber2026.graphoservice.it\/en\/wp-json\/wp\/v2\/application-tag?post=32483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}